{"id":3321,"date":"2025-07-04T12:56:00","date_gmt":"2025-07-04T11:56:00","guid":{"rendered":"https:\/\/www.felixgiralt.com\/productos\/sense%20categoria\/escombra-via-plast\/"},"modified":"2025-07-09T11:36:18","modified_gmt":"2025-07-09T10:36:18","slug":"escombra-via-plast","status":"publish","type":"product","link":"https:\/\/www.felixgiralt.com\/ca\/productes\/escombres\/serie-mill-plast\/escombra-via-plast\/","title":{"rendered":"ESCOMBRA VIA-PLAST"},"content":{"rendered":"<p>Escombra plana cosida amb fibra de secci\u00f3 d\u2019estrella ondulada, de polipropil\u00e8 reciclat i tac de polietil\u00e8.<\/p>\n<p>Amb un pes aproximat de 350g, una longitud de sortida de fibra de 210mm i un ample d&#8217;escombrada de 370mm, \u00e9s un model ideal per a la neteja vi\u00e0ria, industrial, d\u2019exteriors i jardineria.<\/p>\n<p>L&#8217;embalatge dels recanvis \u00e9s de 20 unitats per caixa.<\/p>\n<p>Compatible amb tots els nostres m\u00e0necs amb rosca, de fusta, alumini o met\u00e0l\u00b7lics folrats de longitud des de 80cm fins a 1,5m. Els m\u00e0necs recomanats s\u00f3n el d&#8217;alumini anoditzat amb rosca(ref-150014, de longitud d&#8217;1,50m i di\u00e0metre de 22mm.) i el m\u00e0nec de fusta amb rosca(ref-150004, de longitud 1,35m i di\u00e0metre 22mm.)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Escombra plana cosida amb fibra de polipropil\u00e8 reciclat. Ideal per a la neteja industrial, la neteja d&#8217;exteriors i jardineria.<\/p>\n","protected":false},"featured_media":417,"template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[47,45],"product_tag":[73,74,75],"class_list":["post-3321","product","type-product","status-publish","has-post-thumbnail","product_cat-serie-mill-plast","product_cat-escombres","product_tag-viaria-i-zones-verdes","product_tag-industrial-i-llar","product_tag-jardineria","first","instock","product-type-simple"],"_links":{"self":[{"href":"https:\/\/www.felixgiralt.com\/ca\/wp-json\/wp\/v2\/product\/3321","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.felixgiralt.com\/ca\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.felixgiralt.com\/ca\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.felixgiralt.com\/ca\/wp-json\/wp\/v2\/media\/417"}],"wp:attachment":[{"href":"https:\/\/www.felixgiralt.com\/ca\/wp-json\/wp\/v2\/media?parent=3321"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.felixgiralt.com\/ca\/wp-json\/wp\/v2\/product_brand?post=3321"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.felixgiralt.com\/ca\/wp-json\/wp\/v2\/product_cat?post=3321"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.felixgiralt.com\/ca\/wp-json\/wp\/v2\/product_tag?post=3321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}